{"id":10723,"date":"2026-07-08T23:30:07","date_gmt":"2026-07-08T21:30:07","guid":{"rendered":"https:\/\/nowy.commplace.pl\/?post_type=offer&#038;p=10723"},"modified":"2026-07-25T16:02:59","modified_gmt":"2026-07-25T14:02:59","slug":"strategia-komunikacji-nowa","status":"publish","type":"offer","link":"https:\/\/commplace.pl\/en\/strategia-komunikacji\/","title":{"rendered":"Communication strategy"},"parent":0,"menu_order":0,"template":"","class_list":["post-10723","offer","type-offer","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strategia komunikacji - Commplace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/commplace.pl\/en\/strategia-komunikacji\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strategia komunikacji - Commplace\" \/>\n<meta property=\"og:url\" content=\"https:\/\/commplace.pl\/en\/strategia-komunikacji\/\" \/>\n<meta property=\"og:site_name\" content=\"Commplace\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-25T14:02:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strategia komunikacji - Commplace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/commplace.pl\/en\/strategia-komunikacji\/","og_locale":"en_GB","og_type":"article","og_title":"Strategia komunikacji - Commplace","og_url":"https:\/\/commplace.pl\/en\/strategia-komunikacji\/","og_site_name":"Commplace","article_modified_time":"2026-07-25T14:02:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/commplace.pl\/en\/strategia-komunikacji\/","url":"https:\/\/commplace.pl\/en\/strategia-komunikacji\/","name":"Strategia komunikacji - Commplace","isPartOf":{"@id":"https:\/\/commplace.pl\/en\/#website"},"datePublished":"2026-07-08T21:30:07+00:00","dateModified":"2026-07-25T14:02:59+00:00","breadcrumb":{"@id":"https:\/\/commplace.pl\/en\/strategia-komunikacji\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/commplace.pl\/en\/strategia-komunikacji\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/commplace.pl\/en\/strategia-komunikacji\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/commplace.pl\/"},{"@type":"ListItem","position":2,"name":"Strategia komunikacji"}]},{"@type":"WebSite","@id":"https:\/\/commplace.pl\/en\/#website","url":"https:\/\/commplace.pl\/en\/","name":"Commplace","description":"PR agency Wroc\u0142aw","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/commplace.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/commplace.pl\/en\/wp-json\/wp\/v2\/offer\/10723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/commplace.pl\/en\/wp-json\/wp\/v2\/offer"}],"about":[{"href":"https:\/\/commplace.pl\/en\/wp-json\/wp\/v2\/types\/offer"}],"version-history":[{"count":10,"href":"https:\/\/commplace.pl\/en\/wp-json\/wp\/v2\/offer\/10723\/revisions"}],"predecessor-version":[{"id":11044,"href":"https:\/\/commplace.pl\/en\/wp-json\/wp\/v2\/offer\/10723\/revisions\/11044"}],"wp:attachment":[{"href":"https:\/\/commplace.pl\/en\/wp-json\/wp\/v2\/media?parent=10723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}