{"id":730,"date":"2020-12-31T14:13:30","date_gmt":"2020-12-31T13:13:30","guid":{"rendered":"http:\/\/cp.devtold.pl\/?post_type=jobs&#038;p=730"},"modified":"2023-05-24T13:26:52","modified_gmt":"2023-05-24T11:26:52","slug":"730","status":"publish","type":"jobs","link":"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/","title":{"rendered":"Verkaufsspezialist"},"template":"","class_list":["post-730","jobs","type-jobs","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Specjalista ds. sprzeda\u017cy - Commplace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Specjalista ds. sprzeda\u017cy - Commplace\" \/>\n<meta property=\"og:url\" content=\"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/\" \/>\n<meta property=\"og:site_name\" content=\"Commplace\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-24T11:26:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vertriebsspezialist - Commplace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/","og_locale":"de_DE","og_type":"article","og_title":"Specjalista ds. sprzeda\u017cy - Commplace","og_url":"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/","og_site_name":"Commplace","article_modified_time":"2023-05-24T11:26:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/","url":"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/","name":"Vertriebsspezialist - Commplace","isPartOf":{"@id":"https:\/\/commplace.pl\/de\/#website"},"datePublished":"2020-12-31T13:13:30+00:00","dateModified":"2023-05-24T11:26:52+00:00","breadcrumb":{"@id":"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/commplace.pl\/de\/jobs\/specjalista-ds-sprzedazy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/commplace.pl\/"},{"@type":"ListItem","position":2,"name":"Specjalista ds. sprzeda\u017cy"}]},{"@type":"WebSite","@id":"https:\/\/commplace.pl\/de\/#website","url":"https:\/\/commplace.pl\/de\/","name":"Kommort","description":"PR-Agentur Breslau","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/commplace.pl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/commplace.pl\/de\/wp-json\/wp\/v2\/jobs\/730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/commplace.pl\/de\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/commplace.pl\/de\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/commplace.pl\/de\/wp-json\/wp\/v2\/media?parent=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}